{"id":5900,"date":"2022-09-27T14:26:34","date_gmt":"2022-09-27T14:26:34","guid":{"rendered":"https:\/\/lncarreira.com.br\/?p=5900"},"modified":"2022-10-04T19:37:08","modified_gmt":"2022-10-04T19:37:08","slug":"empreender-uma-questao-de-perfil-ou-de-habilidades-que-podem-ser-desenvolvidas","status":"publish","type":"post","link":"https:\/\/lncarreira.com.br\/index.php\/2022\/09\/27\/empreender-uma-questao-de-perfil-ou-de-habilidades-que-podem-ser-desenvolvidas\/","title":{"rendered":"EMPREENDER: Uma quest\u00e3o de perfil ou de habilidades que podem ser desenvolvidas?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Essa semana ouvi de dois profissionais as seguintes coloca\u00e7\u00f5es: \u201ceu tenho muita vontade de passar meu conhecimento, depois do curso de consultoria, sei que um dia quero fazer isso (&#8230;) N\u00e3o quero mais atuar em empresas, as coisas funcionam at\u00e9 determinado ponto, em consultoria, voc\u00ea faz o projeto, conclui e assume um novo (&#8230;)\u201d<br><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essas duas situa\u00e7\u00f5es me fizeram refletir ainda mais, que muitos profissionais idealizam o empreender. Na fala parece ser muito simples, ter\u00e3o bons desafios, v\u00e3o aplicar seus conhecimentos e ajudar o outro. Mas se sabe que vai muito al\u00e9m disso. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>A\u00ed te pergunto: Empreender \u00e9 uma quest\u00e3o de perfil ou de habilidades desenvolvidas? Eu diria que se precisa ter perfil e desenvolver ainda mais suas habilidades, principalmente aquelas que voc\u00ea nem sabe que possui com tanta clareza. &nbsp;J\u00e1 pensou que voc\u00ea ser\u00e1 desde o vendedor do seu neg\u00f3cio at\u00e9 o financeiro que ir\u00e1 cobrar a conta final?<\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"307\" src=\"https:\/\/lncarreira.com.br\/wp-content\/uploads\/2022\/09\/Imagem-Corpo-Texto-Artigo-Site-1024x307.png\" alt=\"\" class=\"wp-image-5901\" srcset=\"https:\/\/lncarreira.com.br\/wp-content\/uploads\/2022\/09\/Imagem-Corpo-Texto-Artigo-Site-1024x307.png 1024w, https:\/\/lncarreira.com.br\/wp-content\/uploads\/2022\/09\/Imagem-Corpo-Texto-Artigo-Site-300x90.png 300w, https:\/\/lncarreira.com.br\/wp-content\/uploads\/2022\/09\/Imagem-Corpo-Texto-Artigo-Site-768x230.png 768w, https:\/\/lncarreira.com.br\/wp-content\/uploads\/2022\/09\/Imagem-Corpo-Texto-Artigo-Site-1536x461.png 1536w, https:\/\/lncarreira.com.br\/wp-content\/uploads\/2022\/09\/Imagem-Corpo-Texto-Artigo-Site-500x150.png 500w, https:\/\/lncarreira.com.br\/wp-content\/uploads\/2022\/09\/Imagem-Corpo-Texto-Artigo-Site-800x240.png 800w, https:\/\/lncarreira.com.br\/wp-content\/uploads\/2022\/09\/Imagem-Corpo-Texto-Artigo-Site-1280x384.png 1280w, https:\/\/lncarreira.com.br\/wp-content\/uploads\/2022\/09\/Imagem-Corpo-Texto-Artigo-Site-1920x576.png 1920w, https:\/\/lncarreira.com.br\/wp-content\/uploads\/2022\/09\/Imagem-Corpo-Texto-Artigo-Site.png 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Vamos falar de alguns pontos importantes nesse para esse perfil:<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Iniciativa:<\/strong> O profissional precisa ter iniciativa para a\u00e7\u00e3o e realiza\u00e7\u00e3o, um perfil que assume riscos.<\/li><li><strong>Lideran\u00e7a: <\/strong>Importante entender o outro, se colocar e direcionar seu projeto dentro das perspectivas alinhadas, por mais que n\u00e3o tenha uma equipe na sua empresa, possivelmente ter\u00e1 uma equipe no cliente que aplicar\u00e1 o projeto junto com voc\u00ea.<\/li><li><strong>Persist\u00eancia e resili\u00eancia<\/strong>: Na maioria das vezes n\u00e3o dar\u00e1 certo em um primeiro momento, n\u00e3o poder\u00e1 desistir na primeira, caso realmente acredite no projeto.<\/li><li><strong>Planejamento<\/strong>: Importante estar atento as movimenta\u00e7\u00f5es e direcionamento que a empresa far\u00e1, analisar e monitorar os resultados \u00e9 importante.<\/li><li><strong>Vis\u00e3o empreendedora: <\/strong>Entender do neg\u00f3cio que ir\u00e1 atuar, assim como, se manter atualizado sobre esse mercado, far\u00e1 que tenha maior percep\u00e7\u00e3o de atualidade e futuro;<\/li><li><strong>Conhecimento: <\/strong>Ter <em>Know-How<\/em> na \u00e1rea que ir\u00e1 atuar, ser\u00e1 um grande diferencial.<\/li><li><strong>Capacita\u00e7\u00e3o: <\/strong>Por mais que domine sua \u00e1rea e seja refer\u00eancia, \u00e9 muito importante que esteja atualizado sempre, tanto nos aspectos t\u00e9cnicos como habilidades comportamentais, e principalmente nas habilidades comportamentais.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Com certeza listar\u00edamos outros in\u00fameros pontos que s\u00e3o importantes para compor esse perfil, mas diria que esses seriam alguns dos principais. Entender seu perfil a partir de processos de autoconhecimentos, o ajudar\u00e1 compreender para qual desafio seu perfil \u00e9 aderente.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"307\" src=\"https:\/\/lncarreira.com.br\/wp-content\/uploads\/2022\/08\/5.8.22Rodape-Artigo-1024x307.png\" alt=\"\" class=\"wp-image-5830\" srcset=\"https:\/\/lncarreira.com.br\/wp-content\/uploads\/2022\/08\/5.8.22Rodape-Artigo-1024x307.png 1024w, https:\/\/lncarreira.com.br\/wp-content\/uploads\/2022\/08\/5.8.22Rodape-Artigo-300x90.png 300w, https:\/\/lncarreira.com.br\/wp-content\/uploads\/2022\/08\/5.8.22Rodape-Artigo-768x230.png 768w, https:\/\/lncarreira.com.br\/wp-content\/uploads\/2022\/08\/5.8.22Rodape-Artigo-1536x461.png 1536w, https:\/\/lncarreira.com.br\/wp-content\/uploads\/2022\/08\/5.8.22Rodape-Artigo-500x150.png 500w, https:\/\/lncarreira.com.br\/wp-content\/uploads\/2022\/08\/5.8.22Rodape-Artigo-800x240.png 800w, https:\/\/lncarreira.com.br\/wp-content\/uploads\/2022\/08\/5.8.22Rodape-Artigo-1280x384.png 1280w, https:\/\/lncarreira.com.br\/wp-content\/uploads\/2022\/08\/5.8.22Rodape-Artigo-1920x576.png 1920w, https:\/\/lncarreira.com.br\/wp-content\/uploads\/2022\/08\/5.8.22Rodape-Artigo.png 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Essa semana ouvi de dois profissionais as seguintes coloca\u00e7\u00f5es: \u201ceu tenho muita vontade de passar meu conhecimento, depois do curso de consultoria, sei que um dia quero fazer isso (&#8230;) N\u00e3o quero mais atuar em empresas, as coisas funcionam at\u00e9 determinado ponto, em consultoria, voc\u00ea faz o projeto, conclui e assume um novo (&#8230;)\u201d Essas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5902,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"categories":[3],"tags":[14,44,15,52,43],"class_list":["post-5900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","tag-business","tag-career","tag-corporate","tag-lncarreira","tag-transition"],"_links":{"self":[{"href":"https:\/\/lncarreira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lncarreira.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lncarreira.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lncarreira.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lncarreira.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5900"}],"version-history":[{"count":6,"href":"https:\/\/lncarreira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5900\/revisions"}],"predecessor-version":[{"id":5920,"href":"https:\/\/lncarreira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5900\/revisions\/5920"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lncarreira.com.br\/index.php\/wp-json\/wp\/v2\/media\/5902"}],"wp:attachment":[{"href":"https:\/\/lncarreira.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lncarreira.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lncarreira.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}